{"id":415,"count":1717,"description":"","link":"https:\/\/24craftsme.com\/media\/genre\/family\/","name":"Family","slug":"family","taxonomy":"genres","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/genres\/415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/genres"}],"about":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/taxonomies\/genres"}],"wp:post_type":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/tvshows?genres=415"},{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/movies?genres=415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}