{"id":83005,"count":1,"description":"","link":"https:\/\/24craftsme.com\/media\/director\/elizabeth-fowler\/","name":"Elizabeth Fowler","slug":"elizabeth-fowler","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtdirector\/83005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}],"wp:post_type":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/movies?dtdirector=83005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}