{"id":108610,"count":2,"description":"","link":"https:\/\/24craftsme.com\/media\/director\/antoine-de-caunes\/","name":"Antoine de Caunes","slug":"antoine-de-caunes","taxonomy":"dtdirector","meta":[],"_links":{"self":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtdirector\/108610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtdirector"}],"about":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/taxonomies\/dtdirector"}],"wp:post_type":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/movies?dtdirector=108610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}