{"id":88459,"count":1,"description":"","link":"https:\/\/24craftsme.com\/media\/cast\/stephanie-bauder\/","name":"Stephanie Bauder","slug":"stephanie-bauder","taxonomy":"dtcast","meta":[],"_links":{"self":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtcast\/88459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtcast"}],"about":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/taxonomies\/dtcast"}],"wp:post_type":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/tvshows?dtcast=88459"},{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/movies?dtcast=88459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}