{"id":41340,"count":2,"description":"","link":"https:\/\/24craftsme.com\/media\/cast\/jose-martinez-blanco\/","name":"Jos\u00e9 Mart\u00ednez Blanco","slug":"jose-martinez-blanco","taxonomy":"dtcast","meta":[],"_links":{"self":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtcast\/41340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtcast"}],"about":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/taxonomies\/dtcast"}],"wp:post_type":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/tvshows?dtcast=41340"},{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/movies?dtcast=41340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}