{"id":38692,"count":1,"description":"","link":"https:\/\/24craftsme.com\/media\/cast\/margie-lester\/","name":"Margie Lester","slug":"margie-lester","taxonomy":"dtcast","meta":[],"_links":{"self":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtcast\/38692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/dtcast"}],"about":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/taxonomies\/dtcast"}],"wp:post_type":[{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/tvshows?dtcast=38692"},{"href":"https:\/\/24craftsme.com\/media\/wp-json\/wp\/v2\/movies?dtcast=38692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}